{"id":66876,"date":"2026-07-15T08:14:52","date_gmt":"2026-07-15T11:14:52","guid":{"rendered":"https:\/\/www.radiopresidenteibanez.cl\/web\/?p=66876"},"modified":"2026-07-15T08:14:57","modified_gmt":"2026-07-15T11:14:57","slug":"autoridades-regionales-invitan-a-ninas-y-mujeres-demagallanes-a-postular-al-premio-inspiratec-2026","status":"publish","type":"post","link":"https:\/\/www.radiopresidenteibanez.cl\/web\/autoridades-regionales-invitan-a-ninas-y-mujeres-demagallanes-a-postular-al-premio-inspiratec-2026\/","title":{"rendered":"Autoridades regionales invitan a ni\u00f1as y mujeres deMagallanes a postular al Premio InspiraTEC 2026"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Promover el talento femenino, reducir las brechas de participaci\u00f3n en \u00e1reas STEM y<br>visibilizar proyectos que nacen desde las regiones son los principales objetivos del Premio<br>InspiraTEC 2026, cuya convocatoria fue presentada en Magallanes durante una actividad<br>realizada en la sede Punta Arenas de INACAP.<br>El lanzamiento regional reuni\u00f3 a la delegada presidencial regional, Ericka Far\u00edas; el seremi<br>de Econom\u00eda, Fomento y Turismo, Francisco Birke; el seremi de Ciencia, Tecnolog\u00eda,<br>Conocimiento e Innovaci\u00f3n de Magallanes, Carlos Olave; la seremi de la Mujer y la<br>Equidad de G\u00e9nero, Gabriela S\u00e1nchez y el seremi de educaci\u00f3n Jos\u00e9 Alvarado quienes<br>destacaron la importancia de generar m\u00e1s oportunidades para que ni\u00f1as y mujeres<br>desarrollen su potencial en disciplinas vinculadas a la innovaci\u00f3n y el emprendimiento.<br>La instancia cont\u00f3 adem\u00e1s con la participaci\u00f3n de Rossana Venegas, representante de la<br>empresa magall\u00e1nica Puro Viento y finalista nacional del Premio InspiraTEC 2025 en la<br>categor\u00eda Empresaria STEM, quien comparti\u00f3 su experiencia con los asistentes. Los<br>proyectos impulsados por Puro Viento han contado con el apoyo de Corfo, fortaleciendo<br>el desarrollo de iniciativas innovadoras desde la Regi\u00f3n de Magallanes.<br>La delegada presidencial regional, Ericka Far\u00edas, valor\u00f3 que la iniciativa cumpla diez a\u00f1os<br>impulsando la participaci\u00f3n femenina en estas \u00e1reas y destac\u00f3 el potencial existente en la<br>regi\u00f3n \u00abEste premio cumple diez a\u00f1os impulsando que m\u00e1s mujeres se interesen por la<br>ciencia y la tecnolog\u00eda. Eso inspira a las mujeres magall\u00e1nicas, porque ya tenemos grandes<br>talentos en nuestra regi\u00f3n. Siempre he pensado que Magallanes es una regi\u00f3n pionera,<br>donde la ciencia, la tecnolog\u00eda y la investigaci\u00f3n no son algo lejano, sino que forman parte<br>de nuestra identidad. Ojal\u00e1 muchas m\u00e1s mujeres se inspiren y postulen a esta nueva<br>versi\u00f3n.\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El seremi de Econom\u00eda, Francisco Birke, llam\u00f3 a las emprendedoras de la regi\u00f3n a<br>participar de esta nueva convocatoria \u00abEn esta d\u00e9cima versi\u00f3n buscamos continuar<br>reconociendo a mujeres que emprenden y desarrollan actividades relacionadas con<br>innovaci\u00f3n y STEM, incentivando que cada vez m\u00e1s formen parte de estas \u00e1reas. La<br>innovaci\u00f3n y el desarrollo de las \u00e1reas STEM son fundamentales porque impulsan el<br>desarrollo productivo sostenible de la Regi\u00f3n de Magallanes.\u00bb<br>Por su parte, el seremi de Ciencia, Carlos Olave, destac\u00f3 que la regi\u00f3n cuenta con<br>condiciones para seguir formando referentes femeninos en ciencia e innovaci\u00f3n \u00abPara<br>nosotros es muy importante que m\u00e1s mujeres participen de esta premiaci\u00f3n y que se<br>reconozcan las ideas e iniciativas que nacen desde nuestra regi\u00f3n. Tenemos mujeres muy<br>emprendedoras y capaces, adem\u00e1s de una pol\u00edtica nacional que busca motivar a ni\u00f1as<br>desde temprana edad a desarrollar este tipo de herramientas vinculadas a la ciencia.\u00bb<br>En tanto, la seremi de la Mujer y la Equidad de G\u00e9nero, Gabriela S\u00e1nchez, enfatiz\u00f3 el<br>aporte de este reconocimiento para avanzar en igualdad de oportunidades \u00abEspacios<br>como InspiraTEC son muy relevantes porque permiten visibilizar los talentos y<br>capacidades de las mujeres y de las ni\u00f1as, contribuyendo a reducir las brechas que a\u00fan<br>existen en carreras STEM. Queremos que ninguna mujer de nuestra regi\u00f3n quede fuera<br>de esta oportunidad, porque Magallanes cuenta con mujeres muy creativas, con grandes<br>proyectos e inspiraci\u00f3n para mostrar.\u00bb<br>Finalmente, Rossana Venegas invit\u00f3 a m\u00e1s mujeres de Magallanes a atreverse a participar,<br>recordando el impacto que tuvo para ella haber sido finalista nacional el a\u00f1o pasado<br>\u00abParticipar el a\u00f1o pasado fue una experiencia muy importante. Signific\u00f3 inspiraci\u00f3n,<br>visibilizar nuestro trabajo y volver a valorar lo que hacemos. Hoy quiero invitar a todas las<br>mujeres de nuestra regi\u00f3n, a las ni\u00f1as interesadas en STEM, a emprendedoras y<br>empresarias, porque estos espacios inspiran a seguir adelante, a reactivar el trabajo que<br>una realiza y a reconocer el valor de lo que est\u00e1 haciendo.\u00bb<br>El Premio InspiraTEC 2026 contempla las categor\u00edas Joven Inspiradora, dirigida a<br>estudiantes de s\u00e9ptimo b\u00e1sico a cuarto medio; Emprendedora STEM, para<br>emprendedoras en etapa inicial; y Empresaria STEM, orientada a empresarias<br>consolidadas. Las postulaciones estar\u00e1n abiertas hasta el 2 de agosto y pueden realizarse<br>a trav\u00e9s del sitio www.premioinspiratec.cl<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Promover el talento femenino, reducir las brechas de participaci\u00f3n en \u00e1reas STEM yvisibilizar proyectos que nacen desde las regiones son los principales objetivos del PremioInspiraTEC 2026, cuya convocatoria fue presentada&#8230; <a class=\"read-more\" href=\"https:\/\/www.radiopresidenteibanez.cl\/web\/autoridades-regionales-invitan-a-ninas-y-mujeres-demagallanes-a-postular-al-premio-inspiratec-2026\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":66877,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-66876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronica"],"_links":{"self":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/posts\/66876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/comments?post=66876"}],"version-history":[{"count":1,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/posts\/66876\/revisions"}],"predecessor-version":[{"id":66878,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/posts\/66876\/revisions\/66878"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/media\/66877"}],"wp:attachment":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/media?parent=66876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/categories?post=66876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/tags?post=66876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}