{"id":62248,"date":"2026-02-06T10:19:00","date_gmt":"2026-02-06T13:19:00","guid":{"rendered":"https:\/\/www.radiopresidenteibanez.cl\/web\/?p=62248"},"modified":"2026-02-05T23:18:37","modified_gmt":"2026-02-06T02:18:37","slug":"servicio-de-biodiversidad-y-areas-protegidas-comienza-a-operar-en-magallanes","status":"publish","type":"post","link":"https:\/\/www.radiopresidenteibanez.cl\/web\/servicio-de-biodiversidad-y-areas-protegidas-comienza-a-operar-en-magallanes\/","title":{"rendered":"SERVICIO DE BIODIVERSIDAD Y \u00c1REAS PROTEGIDAS COMIENZA A OPERAR EN MAGALLANES"},"content":{"rendered":"\n<p>Autoridades sectoriales dieron inicio oficial a las operaciones del Servicio de Biodiversidad<br>y \u00c1reas Protegidas (SBAP) en la regi\u00f3n con mayor extensi\u00f3n de territorio protegido de<br>Chile. Este hito refuerza el compromiso del Estado con la protecci\u00f3n del patrimonio natural<br>y el resguardo de la biodiversidad para las generaciones presentes y futuras, esfuerzo que<br>ha sido posible gracias al trabajo de los \u00faltimos cinco gobiernos, que reconoce que la<br>biodiversidad es base de la vida, del desarrollo y de la identidad de la regi\u00f3n y el pa\u00eds.<br>\u201cEstamos muy contentos de dar inicio oficial al SBAP en Magallanes y con ello a nuestro<br>mandato de cuidar la naturaleza dentro y fuera de las \u00e1reas protegidas. Es un gran<br>desaf\u00edo, ya que Magallanes es la regi\u00f3n que cuenta con mayor territorio protegido y sus<br>ecosistemas son patrimonio natural del pa\u00eds. Esta puesta en marcha nos permitir\u00e1<br>contribuir a sostener las bases ecol\u00f3gicas y, por lo tanto, la vida y el desarrollo sostenible<br>de la mano de las comunidades de la regi\u00f3n y con un fuerte arraigo en la realidad de este<br>territorio\u201d, coment\u00f3 el director regional del SBAP, Alejandro Fern\u00e1ndez.<br>El SBAP forma parte de un cambio estructural en la forma en que el Estado de Chile<br>organiza su acci\u00f3n para la conservaci\u00f3n de la biodiversidad y la gesti\u00f3n de las \u00e1reas<br>protegidas, superando un escenario hist\u00f3rico de dispersi\u00f3n institucional y avanzando hacia<br>un modelo integrado, especializado y con proyecci\u00f3n a largo plazo.<br>\u201cEste hito viene a fortalecer la institucionalidad ambiental de nuestro pa\u00eds, la cual, tras<br>muchos a\u00f1os de trabajo, est\u00e1 completa. Magallanes es la regi\u00f3n que tiene la mayor<br>cantidad de territorio protegido del pa\u00eds y la labor que desarrollar\u00e1 el SBAP ser\u00e1<br>fundamental en su conversaci\u00f3n\u201d, se\u00f1al\u00f3 el seremi del Medio Ambiente, Enrique<br>Rebolledo.<br>Con esta puesta en marcha, el SBAP asume un mandato integral sobre la biodiversidad del<br>territorio nacional, tanto dentro como fuera de \u00e1reas protegidas, conservando, restaurando<br>y velando por el uso sustentable de la biodiversidad.<br>Este cuidado de la naturaleza se realizar\u00e1 a trav\u00e9s de la gesti\u00f3n y administraci\u00f3n de \u00e1reas<br>protegidas, ejecuci\u00f3n de instrumentos de conservaci\u00f3n, fiscalizaci\u00f3n y acciones de<br>valorizaci\u00f3n de la biodiversidad; para la preservaci\u00f3n de los ecosistemas, especies y genes<br>y al bienestar de las generaciones presentes y futuras.<br>Las labores del SBAP se realizar\u00e1n con una fuerte presencia territorial, lo que implica que<br>la conservaci\u00f3n deja de ser una pol\u00edtica predominantemente centralizada y pasa a tener<br>una ejecuci\u00f3n con mayor arraigo regional, implementando pol\u00edticas de conservaci\u00f3n en el<br>territorio; articulando con gobiernos regionales, delegaciones presidenciales y municipios;<br>coordinando con servicios p\u00fablicos sectoriales, cuyas competencias inciden sobre<br>ecosistemas y biodiversidad, y vincul\u00e1ndose con comunidades locales, organizaciones<br>territoriales y actores productivos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Autoridades sectoriales dieron inicio oficial a las operaciones del Servicio de Biodiversidady \u00c1reas Protegidas (SBAP) en la regi\u00f3n con mayor extensi\u00f3n de territorio protegido deChile. Este hito refuerza el compromiso&#8230; <a class=\"read-more\" href=\"https:\/\/www.radiopresidenteibanez.cl\/web\/servicio-de-biodiversidad-y-areas-protegidas-comienza-a-operar-en-magallanes\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":62249,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-62248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronica"],"_links":{"self":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/posts\/62248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/comments?post=62248"}],"version-history":[{"count":1,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/posts\/62248\/revisions"}],"predecessor-version":[{"id":62250,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/posts\/62248\/revisions\/62250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/media\/62249"}],"wp:attachment":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/media?parent=62248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/categories?post=62248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/tags?post=62248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}