{"id":59054,"date":"2025-09-26T08:05:38","date_gmt":"2025-09-26T11:05:38","guid":{"rendered":"https:\/\/www.radiopresidenteibanez.cl\/web\/?p=59054"},"modified":"2025-09-26T08:06:37","modified_gmt":"2025-09-26T11:06:37","slug":"seremi-de-desarrollo-social-y-familia-inicia-capacitacion-a-personas-mayores-sobre-el-registro-social-de-hogares","status":"publish","type":"post","link":"https:\/\/www.radiopresidenteibanez.cl\/web\/seremi-de-desarrollo-social-y-familia-inicia-capacitacion-a-personas-mayores-sobre-el-registro-social-de-hogares\/","title":{"rendered":"SEREMI de Desarrollo Social y Familia inicia capacitaci\u00f3n a personas mayores sobre el Registro Social de Hogares"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Secretar\u00eda de Desarrollo Social y Familia comenz\u00f3 a impartir una serie de charlas informativas sobre el funcionamiento del Registro Social de Hogares (RSH) a los clubes de adultos mayores de Punta Arenas, con la finalidad de fortalecer los v\u00ednculos con organizaciones de la sociedad civil, y el acceso a los beneficios del Estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el mes el septiembre, el equipo del Registro Social de Hogares ha implementado estas charlas a los clubes de personas mayores \u201cLa Nueva Amistad\u201d, \u201cEsperanza\u201d, \u201cSanta Bernardita\u201d y \u201cAlegre Despertar\u201d, contemplando la realizaci\u00f3n de estas para el resto del a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Seremi de Desarrollo Social y Familia, Danilo Mimica, se\u00f1al\u00f3 que \u201ca trav\u00e9s de nuestro equipo nos estamos desplegando a las sedes donde funcionan estos clubes para poder trasmitirles, de manera clara y sencilla, c\u00f3mo hacer uso del Registro Social de Hogares, sistema de informaci\u00f3n que permite caracterizar socioecon\u00f3micamente a las personas, y apoyar los procesos de selecci\u00f3n para acceder a subsidios, aportes y programas sociales. En Magallanes, 157.747 personas se encuentran inscritas en este sistema, que nos permite adem\u00e1s conocer la realidad regional, como por ejemplo, la existencia de 1.745 personas acreditadas como cuidadoras, y que el 51% de los hogares est\u00e1n a cargo de jefaturas femeninas\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En estas instancias, el Seremi Danilo Mimica tambi\u00e9n ha difundido a los integrantes de los clubes informaci\u00f3n sobre el proyecto de ley que busca crear el Sistema Nacional de Apoyos y Cuidados \u201cChile Cuida\u201d, y que dentro de sus principales programas contempla el Red Local de Apoyos y Cuidados, destinado a que las personas en situaci\u00f3n de dependencia funcional severa o moderada mantengan o mejoren el desarrollo de sus actividades diarias y, a la vez, que sus personas cuidadoras conserven o disminuyan su nivel de sobrecarga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta ayuda se concreta mediante un diagn\u00f3stico para definir el tipo de apoyo que se entregar\u00e1, pudiendo acceder a servicios domiciliarios de kinesiolog\u00eda, terapia ocupacional, atenci\u00f3n psicol\u00f3gica, y servicio de apoyo al cuidado en el domicilio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, se han hecho entregas de ejemplares de la Gu\u00eda de Beneficios, Derechos y Garant\u00edas Sociales, publicaci\u00f3n elaborada por el Ministerio de Desarrollo Social y Familia y que explica de forma sencilla y cercana los beneficios que otorga el Estado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Secretar\u00eda de Desarrollo Social y Familia comenz\u00f3 a impartir una serie de charlas informativas sobre el funcionamiento del Registro Social de Hogares (RSH) a los clubes de adultos mayores&#8230; <a class=\"read-more\" href=\"https:\/\/www.radiopresidenteibanez.cl\/web\/seremi-de-desarrollo-social-y-familia-inicia-capacitacion-a-personas-mayores-sobre-el-registro-social-de-hogares\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":59055,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-59054","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronica"],"_links":{"self":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/posts\/59054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/comments?post=59054"}],"version-history":[{"count":0,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/posts\/59054\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/media\/59055"}],"wp:attachment":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/media?parent=59054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/categories?post=59054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/tags?post=59054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}