{"id":53159,"date":"2024-12-20T10:49:00","date_gmt":"2024-12-20T13:49:00","guid":{"rendered":"https:\/\/www.radiopresidenteibanez.cl\/web\/?p=53159"},"modified":"2024-12-20T09:44:17","modified_gmt":"2024-12-20T12:44:17","slug":"sector-periurbano-de-monte-verde-alto-ya-cuenta-con-tendido-electrico","status":"publish","type":"post","link":"https:\/\/www.radiopresidenteibanez.cl\/web\/sector-periurbano-de-monte-verde-alto-ya-cuenta-con-tendido-electrico\/","title":{"rendered":"Sector periurbano de Monte Verde Alto ya cuenta con tendido el\u00e9ctrico"},"content":{"rendered":"\n<p>A partir de esta jornada, el sector periurbano de Monte Verde Alto, ya cuenta con suministro el\u00e9ctrico, gracias al trabajo e inversi\u00f3n realizado por el Gobierno Regional de Magallanes y la empresa Edelmag.<\/p>\n\n\n\n<p>La iniciativa contempl\u00f3 la instalaci\u00f3n de 55 postes el\u00e9ctricos de baja y media tensi\u00f3n, que le permitir\u00e1 que 49 familias del sector ahora puedan contar con un suministro el\u00e9ctrico de manera estable y de gran calidad.<\/p>\n\n\n\n<p>\u201cEsto les cambia radicalmente la vida a las personas de este sector que, hist\u00f3ricamente, pelearon y lucharon por tener sus servicios b\u00e1sicos. Muy contento por llegar con esta necesidad que los vecinos tanto anhelaban\u201d destac\u00f3 el Gobernador Jorge Flies.<\/p>\n\n\n\n<p>Por su parte, Diego D\u00edaz, Subgerente Comercial de la empresa Edelmag, coment\u00f3 que \u201ceste es un proyecto de larga data que, como compa\u00f1\u00eda el\u00e9ctrica, fuimos subsanando, cumplimos con toda la planificaci\u00f3n para su entrega, gracias a una inversi\u00f3n de 150 millones de pesos\u201d.<\/p>\n\n\n\n<p>Karen Acu\u00f1a es la primera vecina beneficiada con el suministro y agradeci\u00f3 que se haya concretado el proyecto, manifestando que \u201cten\u00edamos que usar generadores con bencina que es un gasto enorme, y ahora los ni\u00f1os podr\u00e1n ver televisi\u00f3n, usar los computadores sin estar pendiente de la descarga y podremos tener el refrigerador m\u00e1s lleno sin miedo a que descongelen los productos\u201d.<\/p>\n\n\n\n<p>Sumado a esto, Carolina R\u00edos, Presidenta de la Agrupaci\u00f3n Alto Monte Verde, se\u00f1al\u00f3 que \u201cestamos super contentos con esta noticia. Lo est\u00e1bamos esperando hace siete a\u00f1os. Se sac\u00f3 adelante este proyecto que nos va a cambiar la vida totalmente. Aqu\u00ed se gasta entre diez y 15 mil pesos diarios en combustible y ahora gastaremos 30 mil una sola vez al mes, un cambio radical\u201d. &nbsp;<\/p>\n\n\n\n<p>La instalaci\u00f3n de este nuevo tendido el\u00e9ctrico trae consigo numerosos beneficios para la comunidad, desde la mejora en la calidad del suministro, el fomento para el desarrollo del sector y una considerable mejora en el d\u00eda a d\u00eda de los habitantes de Monte Verde Alto.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de esta jornada, el sector periurbano de Monte Verde Alto, ya cuenta con suministro el\u00e9ctrico, gracias al trabajo e inversi\u00f3n realizado por el Gobierno Regional de Magallanes y&#8230; <a class=\"read-more\" href=\"https:\/\/www.radiopresidenteibanez.cl\/web\/sector-periurbano-de-monte-verde-alto-ya-cuenta-con-tendido-electrico\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":53160,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-53159","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronica"],"_links":{"self":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/posts\/53159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/comments?post=53159"}],"version-history":[{"count":0,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/posts\/53159\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/media\/53160"}],"wp:attachment":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/media?parent=53159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/categories?post=53159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/tags?post=53159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}