{"id":46392,"date":"2024-02-15T10:45:00","date_gmt":"2024-02-15T13:45:00","guid":{"rendered":"https:\/\/www.radiopresidenteibanez.cl\/web\/?p=46392"},"modified":"2024-02-15T10:15:39","modified_gmt":"2024-02-15T13:15:39","slug":"boletin-informativo-matinal-28","status":"publish","type":"post","link":"https:\/\/www.radiopresidenteibanez.cl\/web\/boletin-informativo-matinal-28\/","title":{"rendered":"BOLETIN INFORMATIVO MATINAL"},"content":{"rendered":"\n<p>SATIAGO.- Irina Karamanos, expareja del Presidente Boric,<br>acus\u00f3 a Renovaci\u00f3n Nacional, RN, de \u00aboportunista\u00bb por<br>plantear la posibilidad de presentar un proyecto de ley para<br>restituir el cargo de primera dama.Karamanos habl\u00f3 de \u00abun<br>estilo oportunista el antojo de poner este tema a d\u00edas de la<br>tragedia. Las manifestaciones de cari\u00f1o hacia Cecilia Morel,<br>viuda del expresidente Pi\u00f1era son valiosas en s\u00ed mismas, sin<br>necesidad de usarlas ni de hacerlas ley\u00bb, declar\u00f3.<\/p>\n\n\n\n<p>SANTIAGO.- Una de las impulsoras del proyecto de ley acerca<br>de la primera dama, la diputada Ximena Ossand\u00f3n cuestion\u00f3 a<br>Karamanos apuntar \u00abpor qu\u00e9 una persona que no ten\u00eda v\u00ednculo<br>legal alguno con el Presidente de la Rep\u00fablica llega y<br>desarma toda una institucionalidad que era querida por la<br>ciudadan\u00eda\u00bb. En esta l\u00ednea, indic\u00f3 que Karamanos \u00abdice que<br>lleg\u00f3 al poder para &#8216;desarmarlo&#8217;, y yo me pregunto qui\u00e9n le<br>dio el poder para hacer eso, sin preguntarle a nadie\u00bb,<br>observ\u00f3.<\/p>\n\n\n\n<p>SANTIAGO.- La diputada Ossand\u00f3n a\u00f1adi\u00f3 que \u00abqueremos que la<br>institucionalidad exista como lo hac\u00eda, queremos que haya la<br>libertad de poder asumir esta responsabilidad, o no, pero que<br>no se destruya como lo hizo la que era la pareja del<br>Presidente Boric. Me parece que no es justo\u00bb. En concreto, la<br>parlamentaria se\u00f1al\u00f3 que la intenci\u00f3n es que \u00abexista un<br>m\u00ednimo v\u00ednculo legal con el Presidente, o Presidenta, para<br>tomar cargos o decisiones como las que tom\u00f3 Irina<br>Karamanos\u00bb.<\/p>\n\n\n\n<p>TEMUCO.- Acusan un cierre anticipado de las instalaciones,<br>hecho que provoc\u00f3 que un centenar de veh\u00edculos y sus<br>ocupantes tuvieron que pasar la noche en pasos fronterizos<br>con Argentina. El hecho ses suscit\u00f3 en el control Mamuil<br>Malal, en la comuna de Curarrehue, a casi 180 kil\u00f3metros al<br>sureste de Temuco, en la Regi\u00f3n de La Araucan\u00eda. Asimismo,<br>aconteci\u00f3 en el control Cardenal Samor\u00e9, a 119 kil\u00f3metros al<br>este de Osorno, en la vecina Regi\u00f3n de Los Lagos.<\/p>\n\n\n\n<p>TEMUCO.- En tanto, la Delegaci\u00f3n Presidencial de La<br>Araucan\u00eda, responsable del funcionamiento del complejo Mamuil<br>Malal, inform\u00f3 que se est\u00e1n tomando medidas para evitar que<br>las personas pasen la noche en la ruta. Una de esas<br>iniciativas es la extensi\u00f3n del horario de atenci\u00f3n, desde<br>las 19:00 horas hasta las 20:00 horas, lo que en varios casos<br>no se habr\u00eda cumplido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SATIAGO.- Irina Karamanos, expareja del Presidente Boric,acus\u00f3 a Renovaci\u00f3n Nacional, RN, de \u00aboportunista\u00bb porplantear la posibilidad de presentar un proyecto de ley pararestituir el cargo de primera dama.Karamanos habl\u00f3 de&#8230; <a class=\"read-more\" href=\"https:\/\/www.radiopresidenteibanez.cl\/web\/boletin-informativo-matinal-28\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":46393,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-46392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronica"],"_links":{"self":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/posts\/46392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/comments?post=46392"}],"version-history":[{"count":0,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/posts\/46392\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/media\/46393"}],"wp:attachment":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/media?parent=46392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/categories?post=46392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/tags?post=46392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}