{"id":45883,"date":"2024-01-24T11:07:00","date_gmt":"2024-01-24T14:07:00","guid":{"rendered":"https:\/\/www.radiopresidenteibanez.cl\/web\/?p=45883"},"modified":"2024-01-24T10:21:51","modified_gmt":"2024-01-24T13:21:51","slug":"magallanes-a-una-diversidad-de-actores-convoco-la-audiencia-publica-de-cierre-del-plan-de-accion-de-hidrogeno-verde","status":"publish","type":"post","link":"https:\/\/www.radiopresidenteibanez.cl\/web\/magallanes-a-una-diversidad-de-actores-convoco-la-audiencia-publica-de-cierre-del-plan-de-accion-de-hidrogeno-verde\/","title":{"rendered":"Magallanes: a una diversidad de actores convoc\u00f3 la Audiencia P\u00fablica de Cierre del Plan de Acci\u00f3n de Hidr\u00f3geno Verde"},"content":{"rendered":"\n<p>En el Auditorio Ernesto Livacic de la Facultad de Ingenier\u00eda de la Universidad de Magallanes se desarroll\u00f3 la Audiencia P\u00fablica de Cierre del Plan de Acci\u00f3n de Hidr\u00f3geno Verde 2023 \u2013 2030.<\/p>\n\n\n\n<p>La actividad de cierre congreg\u00f3 a una diversidad de actores del mundo energ\u00e9tico procedentes de la academia, el sector privado, el sector p\u00fablico y la ciudadan\u00eda.<\/p>\n\n\n\n<p>En la oportunidad, Profesionales de la Divisi\u00f3n de Pol\u00edticas P\u00fablicas y Estudios del Ministerio de Energ\u00eda, presentaron el borrador del documento que recoge&nbsp;la mirada de la ciudadan\u00eda y de los diferentes actores asociados a la industria energ\u00e9tica.<\/p>\n\n\n\n<p>En este sentido, la Seremi del ramo, Mar\u00eda Luisa Ojeda, coment\u00f3 la importancia de elaborar el Plan de Acci\u00f3n \u201cconsiderando las opiniones y miradas de quienes inciden, participan o se relacionan directa o indirectamente, de una u otra forma con la industria energ\u00e9tica\u201d, dijo.<\/p>\n\n\n\n<p>\u201cComo Gobierno del Presidente Gabriel Boric, la participaci\u00f3n de la ciudadan\u00eda resulta fundamental para la validaci\u00f3n y fortalecimiento de nuestras pol\u00edticas p\u00fablicas; pol\u00edticas p\u00fablicas duraderas, con mirada de Estado\u201d, sostuvo la autoridad regional de Energ\u00eda.<\/p>\n\n\n\n<p><strong>CONTENIDOS DEL BORRADOR<\/strong><\/p>\n\n\n\n<p>El Plan de Acci\u00f3n tiene como objetivo ordenar las acciones de los organismos del Estado que tienen incidencia en el desarrollo de la industria del hidr\u00f3geno verde y sus derivados, adem\u00e1s de establecer y priorizar nuevas acciones necesarias para el despliegue de esta industria; todo esto en un marco de sustentabilidad que se ha integrado en la metodolog\u00eda de elaboraci\u00f3n del Plan.<\/p>\n\n\n\n<p>Es por ello que el Ministerio de Energ\u00eda est\u00e1 recorriendo algunas regiones del pa\u00eds para realizar estas audiencias de cierre (Antofagasta, Valpara\u00edso, RM, Biob\u00edo y Magallanes).<\/p>\n\n\n\n<p>Estas son las mismas regiones en donde se realizaron las audiencias de inicio del proceso participativo, durante abril del 2023.<\/p>\n\n\n\n<p>Adicionalmente, se realizaron 2 rondas de talleres ciudadanos en las mismas regiones, entre mayo y agosto.<\/p>\n\n\n\n<p>La informaci\u00f3n levantada desde la ciudadan\u00eda en esos talleres, adem\u00e1s de otras fuentes, permiti\u00f3 enriquecer el proceso y los contenidos del documento que hoy se presenta.<\/p>\n\n\n\n<p>La gobernanza para la implementaci\u00f3n del Plan de Acci\u00f3n se ancla al Comit\u00e9 de Desarrollo de la Industria de Hidr\u00f3geno Verde<br>que fue creado en 2022; sin embargo, se proponen ajustes a esta gobernanza, entre los que destaca la creaci\u00f3n de gobernanzas regionales lideradas por los Gobiernos Regionales, para el despliegue de la industria del hidr\u00f3geno verde y sus derivados, tomando en cuenta, por cierto, los respectivos contextos territoriales, a fin de coordinarse con otras autoridades locales y actores relevantes del ecosistema regional.<\/p>\n\n\n\n<p>Se espera que el Plan de Acci\u00f3n de Hidr\u00f3geno Verde est\u00e9 terminado y entregado durante el primer semestre del 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el Auditorio Ernesto Livacic de la Facultad de Ingenier\u00eda de la Universidad de Magallanes se desarroll\u00f3 la Audiencia P\u00fablica de Cierre del Plan de Acci\u00f3n de Hidr\u00f3geno Verde 2023&#8230; <a class=\"read-more\" href=\"https:\/\/www.radiopresidenteibanez.cl\/web\/magallanes-a-una-diversidad-de-actores-convoco-la-audiencia-publica-de-cierre-del-plan-de-accion-de-hidrogeno-verde\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":45884,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-45883","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronica"],"_links":{"self":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/posts\/45883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/comments?post=45883"}],"version-history":[{"count":0,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/posts\/45883\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/media\/45884"}],"wp:attachment":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/media?parent=45883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/categories?post=45883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/tags?post=45883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}