{"id":37642,"date":"2023-02-23T10:49:00","date_gmt":"2023-02-23T13:49:00","guid":{"rendered":"https:\/\/www.radiopresidenteibanez.cl\/web\/?p=37642"},"modified":"2023-02-23T09:54:58","modified_gmt":"2023-02-23T12:54:58","slug":"todo-listo-para-la-primera-edicion-del-pali-aike-trail","status":"publish","type":"post","link":"https:\/\/www.radiopresidenteibanez.cl\/web\/todo-listo-para-la-primera-edicion-del-pali-aike-trail\/","title":{"rendered":"<strong>Todo listo para la primera edici\u00f3n del \u201cPali Aike Trail\u201d<\/strong>"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A las once de la ma\u00f1ana del<strong>&nbsp;s\u00e1bado 25 de febrero<\/strong>&nbsp;ser\u00e1 la primera largada del \u201cPali Aike Trail\u201d, certamen deportivo organizado por la Ilustre Municipalidad de San Gregorio, en conjunto con Magallanes Trail Runners (MTR) y con el apoyo de CONAF Magallanes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De manera in\u00e9dita, ciento ochenta participantes atravesar\u00e1n el Parque Nacional Pali Aike, recorrer\u00e1n en forma competitiva los senderos repletos de abundantes cr\u00e1teres y campos de lava que asemejan un&nbsp;<strong>paisaje lunar<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstamos muy contentos porque en pocos d\u00edas 180 personas se inscribieron a esta primera versi\u00f3n del Pali Aike Trail, que ser\u00e1 una&nbsp;<strong>carrera t\u00e9cnica de 7K y 17K<\/strong>. Con esta actividad invitamos a la comunidad a conocer el Parque, recorrer sus senderos geol\u00f3gicos, apreciar la flora y fauna caracter\u00edstica de este lugar de vestigios volc\u00e1nicos. Esperamos que se convierta en un certamen deportivo \u00edcono de Magallanes y permita que m\u00e1s personas de nuestra regi\u00f3n vengan a conocer esta \u00e1rea protegida\u201d, indic\u00f3 Jeannette Andrade, alcaldesa de San Gregorio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El circuito de 17 K parte en la&nbsp;<strong>Laguna Ana<\/strong>, avanza por la&nbsp;<strong>Cueva Pali Aike<\/strong>&nbsp;y luego pasa por un hermoso sendero geol\u00f3gico compuesto de rocas volc\u00e1nicas. En tanto, el trail de 7K comienza en el caracter\u00edstico campo volc\u00e1nico y atraviesa el&nbsp;<strong>Cr\u00e1ter Morada del Diablo<\/strong>. Ambos circuitos culminan en las zonas de merienda y estacionamiento que est\u00e1n pr\u00f3ximas a la Cueva Pali Aike.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La&nbsp;<strong>entrega de kits deportivos<\/strong>, que constan de una polera y n\u00famero de carrera, se realizar\u00e1 en el M\u00f3dulo Central de Zona Franca, sector Boulevard, el jueves 23 de febrero, de 09:00 hrs. a 16:00 hrs. (horario continuado).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la entrega de kit deportivos, se explicar\u00e1 la actividad en detalle a los corredores del \u201cPali Aike Trail 2023\u201d y se difundir\u00e1 informaci\u00f3n tur\u00edstica a la comunidad sobre el Parque Nacional Pali Aike, con el objetivo de incentivar la visita al \u00e1rea protegida de CONAF Magallanes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl Parque Nacional Pali Aike est\u00e1 ubicado a 196 kil\u00f3metros de Punta Arenas, es decir, a s\u00f3lo unas horas en auto y nos visitan 1.200 personas al a\u00f1o. Con esta actividad deportiva, donde los corredores podr\u00e1n recorrer los campos volc\u00e1nicos, ver la magnitud del paisaje que parece de otro planeta, buscamos impulsar el turismo dentro de la regi\u00f3n, queremos que los magall\u00e1nicos vengan a conocer este singular Parque de m\u00e1s de cinco mil hect\u00e1reas que est\u00e1 a s\u00f3lo unas horas de distancia\u201d, indica Neftal\u00ed Arriagada, administrador del Parque Nacional Pali Aike.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego de concluir el certamen deportivo, los participantes almorzar\u00e1n en la comuna de San Gregorio, en la Escuela de Punta Delgada, gracias a la gesti\u00f3n de la Ilustre Municipalidad de San Gregorio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La organizaci\u00f3n del evento proveer\u00e1 de&nbsp;<strong>buses para trasladar a los corredores desde Punta Arenas hacia el Parque Nacional Pali Aike<\/strong>. Los buses saldr\u00e1n desde la UMAG a las 07:00 hrs. y luego retornar\u00e1n a Punta Arenas con los participantes a las 17:00 hrs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, se informa que el d\u00eda s\u00e1bado 25 de febrero el Parque Nacional Pali Aike funcionar\u00e1 de manera normal, albergando la actividad deportiva y recibiendo visitantes. Cabe se\u00f1alar que durante estos meses el Parque Nacional Pali Aike abre sus puertas de martes a domingo desde las 08:30 a las 19:30 hrs. (lunes cerrado).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A las once de la ma\u00f1ana del&nbsp;s\u00e1bado 25 de febrero&nbsp;ser\u00e1 la primera largada del \u201cPali Aike Trail\u201d, certamen deportivo organizado por la Ilustre Municipalidad de San Gregorio, en conjunto con&#8230; <a class=\"read-more\" href=\"https:\/\/www.radiopresidenteibanez.cl\/web\/todo-listo-para-la-primera-edicion-del-pali-aike-trail\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":37643,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-37642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronica"],"_links":{"self":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/posts\/37642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/comments?post=37642"}],"version-history":[{"count":0,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/posts\/37642\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/media\/37643"}],"wp:attachment":[{"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/media?parent=37642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/categories?post=37642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiopresidenteibanez.cl\/web\/wp-json\/wp\/v2\/tags?post=37642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}